{"id":152018,"date":"2023-07-25T15:40:16","date_gmt":"2023-07-25T15:40:16","guid":{"rendered":"https:\/\/hoerbuch.us\/wp\/?p=152018"},"modified":"2023-07-25T15:40:16","modified_gmt":"2023-07-25T15:40:16","slug":"wolf-awert-pentamuria-03-die-saeule-des-lichts-ungekuerzt","status":"publish","type":"post","link":"https:\/\/hoerbuch.us\/wp\/horbucher\/152018\/wolf-awert-pentamuria-03-die-saeule-des-lichts-ungekuerzt\/","title":{"rendered":"Wolf Awert &#8211; Pentamuria 03 &#8211; Die S\u00e4ule des Lichts (Ungek\u00fcrzt)"},"content":{"rendered":"<p>Der dritte und letzte Band der Pentamuria Saga:<\/p>\n<p>Nach dem Fall Ringwalls liegt Pentamuria in Tr\u00fcmmern. Die Magie der Elemente stirbt aus und das Feuerreich beginnt einen gnadenlosen Eroberungszug. In dieser Situation liegt es an Nill, dem letzten Erzmagier und m\u00f6glichen Wandler, Ordnung in das Chaos zu bringen und Sergor-Don aufzuhalten.<\/p>\n<p>Doch der K\u00f6nig des Feuerreichs ist nicht die einzige Bedrohung. Ein neuer, unglaublich m\u00e4chtiger Magier, der sich selbst &#8220;S\u00e4ule des Lichts&#8221; nennt, fordert zusammen mit seinen Anh\u00e4ngern die Herrschaft \u00fcber Pentamuria und zwingt Nill, sich zu entscheiden.<\/p>\n<p>Gelesen von Felix Borrmann.<br \/><a href=\"http:\/\/pichost.biz\/viewer.php?id=viu1690299425b.jpg\"><img decoding=\"async\" src=\"http:\/\/pichost.biz\/thumbs\/viu1690299425b.jpg\" border=\"0\"><\/a><br \/>\n<span class=\"eintrag_text\">Dauer:<\/span> 17:01:00 | <span class=\"eintrag_text\">Format:<\/span> mp3 | <span class=\"eintrag_text\">Gr&ouml;&szlig;e:<\/span> 929 MB<br \/>\n<font>Download:<\/font> <a href=\"http:\/\/hoerbuch.us\/loader\/?d=Wolf Awert &#8211; Pentamuria 03 &#8211; Die S\u00e4ule des Lichts (Ungek\u00fcrzt)&#038;p=http:\/\/pichost.biz\/thumbs\/viu1690299425b.jpg\"><b>HIER KLICKEN<\/b> (kostenlose Anmeldung erforderlich)<\/a><\/p>\n<details>\n<summary>Alternative Download-Optionen anzeigen<\/summary>\n<ul><span class=\"eintrag_download1\">ddownload.com:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_217778.html\" target=\"_blank\" class=\"eintrag_download1_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download2\">Nitroflare.com:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_217779.html\" target=\"_blank\" class=\"eintrag_download2_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download3\">RapidGator.net:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_217780.html\" target=\"_blank\" class=\"eintrag_download3_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download4\">Turbobit.net:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_217781.html\" target=\"_blank\" class=\"eintrag_download4_link\" rel=\"noopener\">Download<\/a><br \/>\n<\/ul>\n<\/details>\n<p><span class=\"eintrag_text\">Passwort:<\/span> www.hoerbuch.us | <span class=\"eintrag_text\">Uploader:<\/span> Surgical Remnants<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der dritte und letzte Band der Pentamuria Saga: Nach dem Fall Ringwalls liegt Pentamuria in Tr\u00fcmmern. Die Magie der Elemente stirbt aus und das Feuerreich beginnt einen gnadenlosen Eroberungszug. In dieser Situation liegt es an Nill, dem letzten Erzmagier und m\u00f6glichen Wandler, Ordnung in das Chaos zu bringen und Sergor-Don aufzuhalten. Doch der K\u00f6nig des [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[33,3],"tags":[],"_links":{"self":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/152018"}],"collection":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/comments?post=152018"}],"version-history":[{"count":0,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/152018\/revisions"}],"wp:attachment":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/media?parent=152018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/categories?post=152018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/tags?post=152018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}