{"id":152384,"date":"2023-07-31T11:11:36","date_gmt":"2023-07-31T11:11:36","guid":{"rendered":"https:\/\/hoerbuch.us\/wp\/?p=152384"},"modified":"2023-07-31T11:11:36","modified_gmt":"2023-07-31T11:11:36","slug":"dirk-van-den-boom-sternkreuzer-proxima-14-piraten-ungekuerzt","status":"publish","type":"post","link":"https:\/\/hoerbuch.us\/wp\/horbucher\/152384\/dirk-van-den-boom-sternkreuzer-proxima-14-piraten-ungekuerzt\/","title":{"rendered":"Dirk van den Boom &#8211; Sternkreuzer Proxima 14 &#8211; Piraten! (Ungek\u00fcrzt)"},"content":{"rendered":"<p>Der Frachter Eliza ruft im Onyx-System um Hilfe. Die Proxima, gerade in der N\u00e4he, erh\u00e4lt den Auftrag, sich darum zu k\u00fcmmern. Offenbar wurde die Eliza von Piraten \u00fcberfallen. Hamilton und seine Techniker sollen das Schiff wieder flott machen, von Kampen k\u00fcmmert sich um die Verletzten. Doch da wendet sich das Blatt&#8230;<\/p>\n<p>Zadiya Ark hat mittlerweile die freie Raumstation Ursa erreicht. Dort gibt es einen f\u00e4higen Chirurgen, der bereit ist, das Geld des Widerstands zu nehmen und Ark in eine Kopie ihrer Halbschwester zu verwandeln. Doch leider hat auch ihr alter Feind Captain Kraus mit seinem Kreuzer Anaconda gerade dort angelegt&#8230;<\/p>\n<p>Gelesen von Matthias L\u00fchn.<br \/><a href=\"http:\/\/pichost.biz\/viewer.php?id=arx1690801743j.jpg\"><img decoding=\"async\" src=\"http:\/\/pichost.biz\/thumbs\/arx1690801743j.jpg\" border=\"0\"><\/a><br \/>\n<span class=\"eintrag_text\">Dauer:<\/span> 02:56:10 | <span class=\"eintrag_text\">Format:<\/span> mp3 | <span class=\"eintrag_text\">Gr&ouml;&szlig;e:<\/span> 169 MB<br \/>\n<font>Download:<\/font> <a href=\"http:\/\/hoerbuch.us\/loader\/?d=Dirk van den Boom &#8211; Sternkreuzer Proxima 14 &#8211; Piraten! (Ungek\u00fcrzt)&#038;p=http:\/\/pichost.biz\/thumbs\/arx1690801743j.jpg\"><b>HIER KLICKEN<\/b> (kostenlose Anmeldung erforderlich)<\/a><\/p>\n<details>\n<summary>Alternative Download-Optionen anzeigen<\/summary>\n<ul><span class=\"eintrag_download1\">DDownload.cm<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_218290.html\" target=\"_blank\" class=\"eintrag_download1_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download2\">Nitroflare.com<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_218291.html\" target=\"_blank\" class=\"eintrag_download2_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download3\">RapidGator.net<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_218292.html\" target=\"_blank\" class=\"eintrag_download3_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download4\">Turbobit.net<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_218293.html\" target=\"_blank\" class=\"eintrag_download4_link\" rel=\"noopener\">Download<\/a><br \/>\n<\/ul>\n<\/details>\n<p><span class=\"eintrag_text\">Passwort:<\/span> www.hoerbuch.us | <span class=\"eintrag_text\">Uploader:<\/span> Surgical Remnants<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Frachter Eliza ruft im Onyx-System um Hilfe. Die Proxima, gerade in der N\u00e4he, erh\u00e4lt den Auftrag, sich darum zu k\u00fcmmern. Offenbar wurde die Eliza von Piraten \u00fcberfallen. Hamilton und seine Techniker sollen das Schiff wieder flott machen, von Kampen k\u00fcmmert sich um die Verletzten. Doch da wendet sich das Blatt&#8230; Zadiya Ark hat mittlerweile [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,64],"tags":[],"_links":{"self":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/152384"}],"collection":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/comments?post=152384"}],"version-history":[{"count":0,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/152384\/revisions"}],"wp:attachment":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/media?parent=152384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/categories?post=152384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/tags?post=152384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}