{"id":153152,"date":"2023-08-17T19:11:33","date_gmt":"2023-08-17T19:11:33","guid":{"rendered":"https:\/\/hoerbuch.us\/wp\/?p=153152"},"modified":"2023-08-17T19:11:33","modified_gmt":"2023-08-17T19:11:33","slug":"oliver-doering-der-vampir-teil-8-die-wahrheit-ueber-vampire","status":"publish","type":"post","link":"https:\/\/hoerbuch.us\/wp\/horspiele\/153152\/oliver-doering-der-vampir-teil-8-die-wahrheit-ueber-vampire\/","title":{"rendered":"Oliver D\u00f6ring &#8211; Der Vampir, Teil 8 &#8211; Die Wahrheit \u00fcber Vampire"},"content":{"rendered":"<p>Aus der geheimen Schrift \u00fcber das Wesen der Vampire: &#8220;Der engste Verb\u00fcndete eines Vampirs ist der von ihm erschaffene Ghoul. Man darf einem Ghoul nicht trauen. Niemals! Seine dem Menschen \u00e4hnliche Gestalt steht im Widerspruch zu seiner triebhaften Unberechenbarkeit, seiner Brutalit\u00e4t und gewaltigen Kraft. Totes Fleisch erregt seine Fresslust. Lebendiges Fleisch seine Aggressivit\u00e4t. Er kann sich nicht lange dagegen wehren. Fr\u00fcher oder sp\u00e4ter verwandelt ihn die Mordlust in eine rei\u00dfende Bestie. Und wehe dem, der ihm dann zu nahe ist.<br \/><a href=\"http:\/\/pichost.biz\/viewer.php?id=arx1692299416n.jpg\"><img decoding=\"async\" src=\"http:\/\/pichost.biz\/thumbs\/arx1692299416n.jpg\" border=\"0\"><\/a><br \/>\n<span class=\"eintrag_text\">Dauer:<\/span> 00:29:15 | <span class=\"eintrag_text\">Format:<\/span> mp3 | <span class=\"eintrag_text\">Gr&ouml;&szlig;e:<\/span> 67 MB<br \/>\n<font>Download:<\/font> <a href=\"http:\/\/hoerbuch.us\/loader\/?d=Oliver D\u00f6ring &#8211; Der Vampir, Teil 8 &#8211; Die Wahrheit \u00fcber Vampire&#038;p=http:\/\/pichost.biz\/thumbs\/arx1692299416n.jpg\"><b>HIER KLICKEN<\/b> (kostenlose Anmeldung erforderlich)<\/a><\/p>\n<details>\n<summary>Alternative Download-Optionen anzeigen<\/summary>\n<ul><span class=\"eintrag_download1\">ddownload.com:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_219406.html\" target=\"_blank\" class=\"eintrag_download1_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download2\">RapidGator.net:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_219407.html\" target=\"_blank\" class=\"eintrag_download2_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download3\">Turbobit.net:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_219408.html\" target=\"_blank\" class=\"eintrag_download3_link\" rel=\"noopener\">Download<\/a><br \/><span class=\"eintrag_download4\">Nitroflare.com:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_219409.html\" target=\"_blank\" class=\"eintrag_download4_link\" rel=\"noopener\">Download<\/a><br \/>\n<\/ul>\n<\/details>\n<p><span class=\"eintrag_text\">Passwort:<\/span> www.hoerbuch.us | <span class=\"eintrag_text\">Uploader:<\/span> Surgical Remnants<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aus der geheimen Schrift \u00fcber das Wesen der Vampire: &#8220;Der engste Verb\u00fcndete eines Vampirs ist der von ihm erschaffene Ghoul. Man darf einem Ghoul nicht trauen. Niemals! Seine dem Menschen \u00e4hnliche Gestalt steht im Widerspruch zu seiner triebhaften Unberechenbarkeit, seiner Brutalit\u00e4t und gewaltigen Kraft. Totes Fleisch erregt seine Fresslust. Lebendiges Fleisch seine Aggressivit\u00e4t. Er kann [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[38,4,65],"tags":[],"_links":{"self":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/153152"}],"collection":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/comments?post=153152"}],"version-history":[{"count":0,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/153152\/revisions"}],"wp:attachment":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/media?parent=153152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/categories?post=153152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/tags?post=153152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}