{"id":83260,"date":"2022-09-25T09:07:08","date_gmt":"2022-09-25T09:07:08","guid":{"rendered":"http:\/\/hoerbuch.us\/wp\/?p=83260"},"modified":"2022-09-25T09:27:55","modified_gmt":"2022-09-25T09:27:55","slug":"wolfgang-hohlbein-killer-city","status":"publish","type":"post","link":"https:\/\/hoerbuch.us\/wp\/horbucher\/83260\/wolfgang-hohlbein-killer-city\/","title":{"rendered":"Wolfgang Hohlbein &#8211; Killer City"},"content":{"rendered":"<p>Seine bevorzugte Waffe ist das Rasiermesser. Mit ihm n\u00e4hert er sich leise aus der Dunkelheit. Er ist auf der Suche nach seinem n\u00e4chsten Opfer, denn sein Impuls zu t\u00f6ten ist \u00fcberm\u00e4chtig&#8230; Thornhill hat schon viele Menschen get\u00f6tet. Die k\u00fcrzlich er\u00f6ffnete Weltausstellung lockt Tausende Besucher nach Chicago. Dort kann er in der Masse der Touristen untertauchen und auf Jagd gehen. Doch schon bald macht er sich Feinde unter den Gangs der Stadt. Schnell sind die ersten Toten zu beklagen &#8211; und Thornhill wird vom J\u00e4ger zum Gejagten.<br \/><a href=\"http:\/\/pichost.biz\/viewer.php?id=opt1664097318e.jpg\"><img decoding=\"async\" src=\"http:\/\/pichost.biz\/thumbs\/opt1664097318e.jpg\" border=\"0\"><\/a><br \/>\n<span class=\"eintrag_text\">Dauer:<\/span> 07:21:00 | <span class=\"eintrag_text\">Format:<\/span> mp3 | <span class=\"eintrag_text\">Gr&ouml;&szlig;e:<\/span> 405 MB<br \/>\n<font>Download:<\/font> <a href=\"http:\/\/hoerbuch.us\/loader\/?d=Wolfgang Hohlbein &#8211; Killer City&#038;p=http:\/\/pichost.biz\/thumbs\/opt1664097318e.jpg\"><b>HIER KLICKEN<\/b> (kostenlose Anmeldung erforderlich)<\/a><\/p>\n<details>\n<summary>Alternative Download-Optionen anzeigen<\/summary>\n<ul><span class=\"eintrag_download1\">Nitroflare.com:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_199956.html\" target=\"_blank\" class=\"eintrag_download1_link\">Download<\/a><br \/><span class=\"eintrag_download2\">RapidGator.net:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_199957.html\" target=\"_blank\" class=\"eintrag_download2_link\">Download<\/a><br \/><span class=\"eintrag_download3\">ddownload.com:<\/span> <a href=\"http:\/\/hoerbuch.us\/download\/?http:\/\/www.hoerbuch.us\/protection\/folder_199958.html\" target=\"_blank\" class=\"eintrag_download3_link\">Download<\/a><br \/>\n<\/ul>\n<\/details>\n<p><span class=\"eintrag_text\">Passwort:<\/span> www.hoerbuch.us | <span class=\"eintrag_text\">Uploader:<\/span> Oldy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seine bevorzugte Waffe ist das Rasiermesser. Mit ihm n\u00e4hert er sich leise aus der Dunkelheit. Er ist auf der Suche nach seinem n\u00e4chsten Opfer, denn sein Impuls zu t\u00f6ten ist \u00fcberm\u00e4chtig&#8230; Thornhill hat schon viele Menschen get\u00f6tet. Die k\u00fcrzlich er\u00f6ffnete Weltausstellung lockt Tausende Besucher nach Chicago. Dort kann er in der Masse der Touristen untertauchen [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,5],"tags":[],"_links":{"self":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/83260"}],"collection":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/comments?post=83260"}],"version-history":[{"count":3,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/83260\/revisions"}],"predecessor-version":[{"id":139150,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/posts\/83260\/revisions\/139150"}],"wp:attachment":[{"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/media?parent=83260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/categories?post=83260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hoerbuch.us\/wp\/wp-json\/wp\/v2\/tags?post=83260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}